{"id":25201,"date":"2025-11-10T15:51:38","date_gmt":"2025-11-10T14:51:38","guid":{"rendered":"https:\/\/www.yellowscan.com\/knowledge\/yellowscan-navigator-lidar%e3%81%ab%e3%82%88%e3%82%8b%e3%83%8e%e3%83%ab%e3%82%a6%e3%82%a7%e3%83%bc%e3%81%ae%e6%b5%b7%e8%8d%89%e7%94%9f%e6%85%8b%e7%b3%bb%e3%81%ae%e3%83%9e%e3%83%83%e3%83%94%e3%83%b3\/"},"modified":"2025-11-10T15:52:36","modified_gmt":"2025-11-10T14:52:36","slug":"mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar","status":"publish","type":"ys_knowledge","link":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/","title":{"rendered":"YellowScan Navigator LiDAR\u306b\u3088\u308b\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u6d77\u8349\u751f\u614b\u7cfb\u306e\u30de\u30c3\u30d4\u30f3\u30b0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"25201\" class=\"elementor elementor-25201 elementor-25155\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-465b21c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"465b21c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c237ead\" data-id=\"c237ead\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2984d5f elementor-widget elementor-widget-text-editor\" data-id=\"2984d5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"h3\">\u30c1\u30e3\u30ec\u30f3\u30b8<\/h2><p>\u30ce\u30eb\u30a6\u30a7\u30fc\u6c34\u7814\u7a76\u6240\uff08NIVA\uff09\u306f\u3001\u6cbf\u5cb8\u57df\u306b\u304a\u3051\u308b\u30c9\u30ed\u30fc\u30f3\u306b\u3088\u308b\u8abf\u67fb\u3001\u30de\u30c3\u30d4\u30f3\u30b0\u3001\u30e2\u30cb\u30bf\u30ea\u30f3\u30b0\u306e\u305f\u3081\u306e\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u30a4\u30f3\u30d5\u30e9\u3067\u3042\u308bSeaBee\u306e\u4e3b\u8981\u30d1\u30fc\u30c8\u30ca\u30fc\u3067\u3042\u308b\u3002\u3053\u306e\u30a4\u30cb\u30b7\u30a2\u30c1\u30d6\u306e\u4e00\u74b0\u3068\u3057\u3066\u3001NIVA\u306f\u5927\u91cf\u306eCO\u2082\u3092\u6355\u6349\u30fb\u8caf\u8535\u3059\u308b\u6d77\u8349\u751f\u614b\u7cfb\u306e\u7814\u7a76\u3092\u76ee\u6307\u3057\u305f\u3002\u305d\u306e\u76ee\u7684\u306f\u3001\u3069\u308c\u3060\u3051\u306e\u70ad\u7d20\u304c\u8caf\u8535\u3055\u308c\u3066\u3044\u308b\u304b\u3092\u8abf\u67fb\u3057\u3001\u3053\u308c\u3089\u306e\u91cd\u8981\u306a\u6c34\u4e2d\u6cbf\u5cb8\u751f\u606f\u5730\u306b\u5bfe\u3059\u308b\u6c17\u5019\u3084\u4eba\u9593\u306e\u5f71\u97ff\u306e\u5f71\u97ff\u3092\u3088\u308a\u3088\u304f\u7406\u89e3\u3059\u308b\u3053\u3068\u3067\u3042\u3063\u305f\u3002  <\/p><p>\u5f93\u6765\u306e\u30e2\u30cb\u30bf\u30ea\u30f3\u30b0\u624b\u6cd5\u3067\u306f\u3001\u6d45\u304f\u30c0\u30a4\u30ca\u30df\u30c3\u30af\u306a\u6cbf\u5cb8\u6c34\u57df\u306b\u5fc5\u8981\u306a\u89e3\u50cf\u5ea6\u304c\u4e0d\u8db3\u3057\u3066\u3044\u305f\u3002\u3053\u306e\u554f\u984c\u3092\u89e3\u6c7a\u3059\u308b\u305f\u3081\u3001NIVA\u306f\u3001\u6d77\u8349\u751f\u606f\u5730\u306e\u4f53\u7a4d\u3092\u5b9a\u91cf\u5316\u3057\u3001\u5730\u4e0a\u30d0\u30a4\u30aa\u30de\u30b9\uff08\u8449\uff09\u306b\u84c4\u7a4d\u3055\u308c\u305f\u70ad\u7d20\u3092\u63a8\u5b9a\u3059\u308b\u305f\u3081\u306b\u3001<a href=\"https:\/\/www.yellowscan.com\/ja\/industries\/bathymetry\/\" target=\"_blank\" rel=\"noopener\">\u30c8\u30dd\u30fb\u30d0\u30a4\u30c8\u30e1\u30c8\u30eaLiDAR\u3092\u7528\u3044\u3066<\/a>\u6c34\u4e2d\u6d77\u8349\u85fb\u5834\u306e3\u6b21\u5143\u30e2\u30c7\u30eb\u3092\u4f5c\u6210\u3059\u308b\u3053\u3068\u306b\u7740\u624b\u3057\u305f\u3002 <\/p><p>\u7814\u7a76\u6a5f\u95a2\u3067\u3042\u308bNIVA\u306f\u3001LiDAR\u306e\u5c02\u9580\u7684\u306a\u8a13\u7df4\u3092\u53d7\u3051\u305f\u79d1\u5b66\u8005\u3084\u6280\u8853\u8005\u3067\u306a\u304f\u3066\u3082\u64cd\u4f5c\u3067\u304d\u308b\u5805\u7262\u306a\u30cf\u30fc\u30c9\u30a6\u30a7\u30a2\u3068\u30bd\u30d5\u30c8\u30a6\u30a7\u30a2\u3092\u63d0\u4f9b\u3059\u308b\u3001\u30a2\u30af\u30bb\u30b9\u3057\u3084\u3059\u304f\u4f7f\u3044\u3084\u3059\u3044\u30bd\u30ea\u30e5\u30fc\u30b7\u30e7\u30f3\u3082\u5fc5\u8981\u3068\u3057\u3066\u3044\u305f\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dabca3a el-section-img-x1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dabca3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-380a1abd\" data-id=\"380a1abd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71d00a0e elementor-widget elementor-widget-image\" data-id=\"71d00a0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/2-2-1024x576.jpg\" class=\"attachment-large size-large wp-image-25166\" alt=\"Photos from field deployment of Navigator, provided by Robert N\u00f8ddebo Poulsen.\" srcset=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/2-2-1024x576.jpg 1024w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/2-2-300x169.jpg 300w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/2-2-768x432.jpg 768w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/2-2-1536x864.jpg 1536w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/2-2-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb7e8e3 el-img-caption elementor-widget elementor-widget-text-editor\" data-id=\"3fb7e8e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u30ed\u30d0\u30fc\u30c8\u30fb\u30ce\u30c3\u30c7\u30dc\u30fb\u30dd\u30a6\u30eb\u30bb\u30f3\u6c0f\u63d0\u4f9b\u306e\u30ca\u30d3\u30b2\u30fc\u30bf\u30fc\u73fe\u5730\u914d\u5099\u6642\u306e\u5199\u771f\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b1f53f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b1f53f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-956604d\" data-id=\"956604d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a333c69 elementor-widget elementor-widget-text-editor\" data-id=\"a333c69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"h3\">\u30bd\u30ea\u30e5\u30fc\u30b7\u30e7\u30f3<\/h2><p>\u3053\u308c\u3092\u5b9f\u73fe\u3059\u308b\u305f\u3081\u3001NIVA\u306fUAV\u642d\u8f09\u306e\u5730\u5f62\u30fb\u6c34\u6df1\u6e2c\u5b9aLiDAR\u30b7\u30b9\u30c6\u30e0\u3067\u3042\u308bYellowScan Navigator\u3092\u3001\u8010\u4e45\u30ed\u30fc\u30bf\u30fc\u30a2\u30fc\u30e0\u3092\u88c5\u5099\u3057\u305fHexadrone Tundra 2\u30c9\u30ed\u30fc\u30f3\u3068\u7d44\u307f\u5408\u308f\u305b\u305f\u3002Navigator\u306fCloudStation Colorization\u3068Terrain Classification\u30e2\u30b8\u30e5\u30fc\u30eb\u3067\u88dc\u5b8c\u3055\u308c\u3001\u76f4\u611f\u7684\u306a\u30c7\u30fc\u30bf\u51e6\u7406\u3068\u690d\u751f\u3068\u6d77\u5e95\u306e\u6b63\u78ba\u306a\u5206\u96e2\u3092\u53ef\u80fd\u306b\u3057\u305f\u3002 <\/p><p>YellowScan\u306e\u30b5\u30dd\u30fc\u30c8\u306f\u3001\u30ad\u30e3\u30f3\u30da\u30fc\u30f3\u4e2d\u306b\u88c5\u7f6e\u306e\u8a2d\u5b9a\u3084\u30c8\u30e9\u30d6\u30eb\u30b7\u30e5\u30fc\u30c6\u30a3\u30f3\u30b0\u306b\u3064\u3044\u3066\u30bf\u30a4\u30e0\u30ea\u30fc\u306a\u30d5\u30a3\u30fc\u30c9\u30d0\u30c3\u30af\u3092\u63d0\u4f9b\u3057\u307e\u3057\u305f\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16dfbe9a el-section-img-x1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16dfbe9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79f319ff\" data-id=\"79f319ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2df0c088 elementor-widget elementor-widget-image\" data-id=\"2df0c088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"573\" src=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/3-1-1024x573.jpg\" class=\"attachment-large size-large wp-image-25171\" alt=\"Screen captures of the point cloud at the study area.\" srcset=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/3-1-1024x573.jpg 1024w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/3-1-300x168.jpg 300w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/3-1-768x430.jpg 768w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/3-1.jpg 1177w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31ccad77 el-img-caption elementor-widget elementor-widget-text-editor\" data-id=\"31ccad77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u8abf\u67fb\u5730\u57df\u306e\u70b9\u7fa4\u306e\u753b\u9762\u30ad\u30e3\u30d7\u30c1\u30e3\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9132383 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9132383\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e4a92f\" data-id=\"0e4a92f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dae786 elementor-widget elementor-widget-text-editor\" data-id=\"1dae786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"h3\">\u30df\u30c3\u30b7\u30e7\u30f3\u30d1\u30e9\u30e1\u30fc\u30bf\u30fc<\/h2><p>\u8abf\u67fb\u30b5\u30a4\u30ba\uff1a0.09km\u00b2\uff5e1,264\u4e07\u70b9\uff08\u6a19\u9ad850m\uff09\u30010.05km\u00b2\uff5e1,265\u4e07\u70b9\uff08\u6a19\u9ad825m\uff09<\/p><ul><li><strong>\u30d5\u30e9\u30a4\u30c8<\/strong>\u5408\u8a082\u4fbf<\/li><li><strong>\u98db\u884c\u6642\u9593\uff1a<\/strong>24\u5206\uff0850m\uff09\uff5c22\u5206\uff0825m\uff09<\/li><li><strong>\u98db\u884c\u9ad8\u5ea6\u3068\u901f\u5ea6\uff1a<\/strong>25m\u306850m\uff5c5m\/s<\/li><li><strong>\u8a2d\u5099<\/strong><ul><li><a href=\"\/products\/navigator\">YellowScan Navigator<\/a>+ \u30ab\u30e1\u30e9\u30e2\u30b8\u30e5\u30fc\u30eb<\/li><li>\u30c4\u30f3\u30c9\u30e92UAV\uff08\u30d8\u30ad\u30b5\u30c9\u30ed\u30fc\u30f3\u3001\u30d5\u30e9\u30f3\u30b9\uff09<\/li><li><a href=\"https:\/\/www.yellowscan.com\/ja\/%E8%A3%BD%E5%93%81\/%E3%82%AF%E3%83%A9%E3%82%A6%E3%83%89%E3%82%B9%E3%83%86%E3%83%BC%E3%82%B7%E3%83%A7%E3%83%B3\/\">CloudStation\u306e\u30ab\u30e9\u30fc<\/a>\u5316\u3068\u5730\u5f62\u5206\u985e<\/li><li>CloudCompare\uff08\u624b\u52d5\u691c\u67fb\/\u30af\u30ea\u30fc\u30cb\u30f3\u30b0\u7528\uff09<\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-21a84760 el-section-full el-section-img-x2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21a84760\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-58271fb4\" data-id=\"58271fb4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e1335f3 elementor-widget elementor-widget-image\" data-id=\"4e1335f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"468\" src=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/4-1-1024x468.jpg\" class=\"attachment-large size-large wp-image-25176\" alt=\"Screen captures of the point clouds at the study area.\" srcset=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/4-1-1024x468.jpg 1024w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/4-1-300x137.jpg 300w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/4-1-768x351.jpg 768w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/4-1-1536x701.jpg 1536w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/4-1-2048x935.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69f9f6ed el-img-caption elementor-widget elementor-widget-text-editor\" data-id=\"69f9f6ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u8abf\u67fb\u5730\u57df\u306e\u70b9\u7fa4\u306e\u30b9\u30af\u30ea\u30fc\u30f3\u30ad\u30e3\u30d7\u30c1\u30e3\u3002  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-444c501f\" data-id=\"444c501f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18bb0542 elementor-widget elementor-widget-image\" data-id=\"18bb0542\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"437\" src=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/5-1-1024x437.png\" class=\"attachment-large size-large wp-image-25181\" alt=\"Screen captures of the point cloud at the study area\" srcset=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/5-1-1024x437.png 1024w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/5-1-300x128.png 300w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/5-1-768x328.png 768w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/5-1-1536x656.png 1536w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/5-1-2048x875.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-598e58ac el-img-caption elementor-widget elementor-widget-text-editor\" data-id=\"598e58ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u8abf\u67fb\u5730\u57df\u306e\u70b9\u7fa4\u306e\u30b9\u30af\u30ea\u30fc\u30f3\u30ad\u30e3\u30d7\u30c1\u30e3\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fef45c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fef45c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53fe0eb\" data-id=\"53fe0eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e71671 elementor-widget elementor-widget-text-editor\" data-id=\"4e71671\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"h3\">\u7d50\u679c<\/h2><p><a href=\"\/products\/navigator\">YellowScan Navigator\u306e<\/a>\u30dd\u30a4\u30f3\u30c8\u5bc6\u5ea6\u306f50 m AGL\u306770 pts\/m\u00b2\u300125 m AGL\u3067125 pts\/m\u00b2\u3067\u3001\u6c34\u5e73\u30fb\u5782\u76f4\u7cbe\u5ea6\u306f\u98db\u884c\u9ad8\u3055\u306b\u3088\u308a0.01\uff5e0.015 m\u3067\u3057\u305f\u3002<\/p><p><a href=\"https:\/\/www.yellowscan.com\/ja\/%E8%A3%BD%E5%93%81\/%E3%82%AF%E3%83%A9%E3%82%A6%E3%83%89%E3%82%B9%E3%83%86%E3%83%BC%E3%82%B7%E3%83%A7%E3%83%B3\/\">YellowScan CloudStation\u30bd\u30d5\u30c8\u30a6\u30a7\u30a2\u306e<\/a>\u5730\u5f62\u5206\u985e\u6a5f\u80fd\u3092\u4f7f\u3044\u3001\u751f\u306e\u70b9\u7fa4\u3092\u9678\u5730\u3001\u6c34\u9762\u3001\u6c34\u67f1\u30ce\u30a4\u30ba\u3001\u6d77\u5e95\u306b\u5206\u96e2\u3057\u305f\u3002\u624b\u4f5c\u696d\u306b\u3088\u308b\u30af\u30ea\u30fc\u30cb\u30f3\u30b0\u306e\u5f8c\u3001\u6d77\u5e95\u70b9\u306e\u307f\u304c\u4fdd\u6301\u3055\u308c\u3001\u70b9\u5f37\u5ea6\u304c\u6700\u3082\u91cd\u8981\u306a\u5909\u6570\u3067\u3042\u308b\u30e9\u30f3\u30c0\u30e0\u30d5\u30a9\u30ec\u30b9\u30c8\u30e2\u30c7\u30eb\u3067\u3055\u3089\u306b\u7cbe\u7dfb\u5316\u3055\u308c\u3001\u690d\u751f\u3068\u771f\u306e\u6d77\u5e95\uff08\u7802\u3068\u5ca9\uff09\u3092\u533a\u5225\u3057\u305f\u3002 <\/p><p>\u3053\u306e\u30ef\u30fc\u30af\u30d5\u30ed\u30fc\u306b\u3088\u308a\u3001\u690d\u751f\u30ad\u30e3\u30ce\u30d4\u30fc\u306e\u9ad8\u89e3\u50cf\u5ea6\u30c7\u30b8\u30bf\u30eb\u30b5\u30fc\u30d5\u30a7\u30b9\u30e2\u30c7\u30eb\uff08DSM\uff09\u3068\u6d77\u5e95\u306e\u30c7\u30b8\u30bf\u30eb\u5730\u5f62\u30e2\u30c7\u30eb\uff08DTM\uff09\u3092\u3001\u3068\u3082\u306b10cm\u306e\u89e3\u50cf\u5ea6\u3067\u4f5c\u6210\u3059\u308b\u3053\u3068\u304c\u3067\u304d\u305f\u3002DSM\u304b\u3089DTM\u3092\u5dee\u3057\u5f15\u304f\u3053\u3068\u3067\u3001\u3053\u306e\u30ec\u30d9\u30eb\u306e\u8a73\u7d30\u3055\u3067\u521d\u3081\u3066\u6c34\u4e2d\u6d77\u8349\u306e\u6a39\u51a0\u9ad8\u30e2\u30c7\u30eb\u304c\u4f5c\u6210\u3055\u308c\u3001NIVA\u306f\u751f\u606f\u5730\u306e\u4f53\u7a4d\u3092\u5b9a\u91cf\u5316\u3057\u3001\u5730\u4e0a\u90e8\u30d0\u30a4\u30aa\u30de\u30b9\u306e\u70ad\u7d20\u6355\u7372\u91cf\u3092\u63a8\u5b9a\u3067\u304d\u308b\u3088\u3046\u306b\u306a\u3063\u305f\u3002 <\/p><p>\u79d1\u5b66\u7684\u306b\u306f\u3001Navigator\u306f\u7a7a\u4e2dLiDAR\u8abf\u67fb\u3088\u308a\u3082\u4e00\u6841\u9ad8\u3044\u70b9\u7fa4\u5bc6\u5ea6\u3092\u63d0\u4f9b\u3057\u3001\u6c34\u4e2d\u690d\u751f\u306e\u524d\u4f8b\u306e\u306a\u30443D\u30e2\u30c7\u30ea\u30f3\u30b0\u3092\u53ef\u80fd\u306b\u3057\u307e\u3057\u305f\u3002\u3053\u306e\u30b7\u30b9\u30c6\u30e0\u306f\u6b63\u78ba\u3067\u518d\u73fe\u6027\u304c\u9ad8\u304f\u3001\u8cbb\u7528\u5bfe\u52b9\u679c\u304c\u9ad8\u304f\u3001\u76f4\u611f\u7684\u306b\u64cd\u4f5c\u3067\u304d\u308b\u3053\u3068\u304c\u8a3c\u660e\u3055\u308c\u3001CloudStation\u306e\u5206\u985e\u3068\u5f37\u5ea6\u88dc\u6b63\u30c4\u30fc\u30eb\u306f\u51e6\u7406\u3092\u5927\u5e45\u306b\u8fc5\u901f\u5316\u3057\u305f\u3002\u30c9\u30ed\u30fc\u30f3\u642d\u8f09\u306eNavigator\u306f\u3001\u822a\u7a7a\u6a5f\u642d\u8f09\u306eLiDAR\u3068\u6bd4\u8f03\u3057\u3066\u3001\u3088\u308a\u5b89\u4fa1\u3067\u5b89\u5168\u306b\u8abf\u67fb\u3092\u5b9f\u65bd\u3067\u304d\u308b\u3060\u3051\u3067\u306a\u304f\u3001\u5c06\u6765\u306e\u6d45\u6d77\u57df\u751f\u606f\u57df\u30e2\u30cb\u30bf\u30ea\u30f3\u30b0\u30fb\u30ad\u30e3\u30f3\u30da\u30fc\u30f3\u306b\u304a\u3044\u3066\u3001\u3088\u308a\u7c21\u5358\u306b\u518d\u73fe\u3067\u304d\u308b\u3088\u3046\u306b\u306a\u308a\u307e\u3057\u305f\u3002  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78f4cc46 elm-testimonial elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78f4cc46\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67c5a5c5\" data-id=\"67c5a5c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50421cdf elm-testimonial__text elementor-widget elementor-widget-text-editor\" data-id=\"50421cdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>YellowScan Navigator LiDAR\u30b7\u30b9\u30c6\u30e0\u306f\u3001\u9ad8\u54c1\u8cea\u306a\u70b9\u7fa4\u30c7\u30fc\u30bf\u3092\u76f4\u611f\u7684\u304b\u3064\u8fc5\u901f\u306b\u30c7\u30fc\u30bf\u51e6\u7406\u3067\u304d\u308b\u305f\u3081\u3001\u7814\u7a76\u8005\u3084\u81ea\u7136\u8cc7\u6e90\u7ba1\u7406\u8005\u306b\u3068\u3063\u3066\u7406\u60f3\u7684\u306a\u30b7\u30b9\u30c6\u30e0\u3067\u3059\u3002\u3053\u306e\u30b7\u30b9\u30c6\u30e0\u306f\u3001\u6d45\u6d77\u57df\u306e\u751f\u606f\u5730\u30de\u30c3\u30d4\u30f3\u30b0\u306e\u6b21\u306e\u30b9\u30c6\u30c3\u30d7\u3068\u306a\u308b\u3082\u306e\u3067\u3001\u5f93\u6765\u306e\u6e2c\u91cf\u65b9\u6cd5\u306b\u6bd4\u3079\u3001\u8cbb\u7528\u5bfe\u52b9\u679c\u304c\u9ad8\u304f\u3001\u518d\u73fe\u53ef\u80fd\u3067\u3001\u9ad8\u89e3\u50cf\u5ea6\u306e\u7d50\u679c\u3092\u5f97\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002 <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7014525 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7014525\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-65645ed6\" data-id=\"65645ed6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-390aa583 elm-testimonial__img elementor-widget elementor-widget-image\" data-id=\"390aa583\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/Charles-Lavin.jpg\" class=\"attachment-large size-large wp-image-25191\" alt=\"Charles P.Lavin, PhD, researcher at the Norwegian Institute for Water Research (NIVA) &amp; SeaBee\" srcset=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/Charles-Lavin.jpg 512w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/Charles-Lavin-300x300.jpg 300w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/Charles-Lavin-150x150.jpg 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6daa6c24\" data-id=\"6daa6c24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3866c4a2 elementor-widget elementor-widget-text-editor\" data-id=\"3866c4a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong><span class=\"elm-testimonials__name\">\u30c1\u30e3\u30fc\u30eb\u30ba\u30fbP\u30fb\u30e9\u30f4\u30a3\u30f3<\/span><\/strong>\n\n<span class=\"elm-testimonials__role\"><em><strong>\u535a\u58eb\u53f7\u3001\u7814\u7a76\u54e1<\/strong>-\u30ce\u30eb\u30a6\u30a7\u30fc\u6c34\u7814\u7a76\u6240\uff08NIVA\uff09\uff06SeaBee<\/em>\n<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a9d4139 el-section-img-x1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a9d4139\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-471852ac\" data-id=\"471852ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ff96d5e elementor-widget elementor-widget-image\" data-id=\"5ff96d5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"607\" src=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/6-1-1024x607.png\" class=\"attachment-large size-large wp-image-25186\" alt=\"Canopy height model imposed over an RGB drone image of the study site, including the surveyed eelgrass bed.\" srcset=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/6-1-1024x607.png 1024w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/6-1-300x178.png 300w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/6-1-768x455.png 768w, https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/6-1.png 1389w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35fa0e41 el-img-caption elementor-widget elementor-widget-text-editor\" data-id=\"35fa0e41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u30a2\u30de\u30e2\u5834\u3092\u542b\u3080\u8abf\u67fb\u5730\u70b9\u306eRGB\u30c9\u30ed\u30fc\u30f3\u753b\u50cf\u306b\u9069\u7528\u3055\u308c\u305f\u6a39\u51a0\u9ad8\u30e2\u30c7\u30eb\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":25161,"menu_order":17,"template":"","meta":{"_acf_changed":false,"content-type":""},"categories":[75],"class_list":["post-25201","ys_knowledge","type-ys_knowledge","status-publish","has-post-thumbnail","hentry","category-success-story"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>YellowScan Navigator LiDAR\u306b\u3088\u308b\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u6d77\u8349\u751f\u614b\u7cfb\u306e\u30de\u30c3\u30d4\u30f3\u30b0 - YellowScan<\/title>\n<meta name=\"description\" content=\"NIVA\u304cYellowScan Navigator\u3092\u4f7f\u3063\u3066\u6c34\u4e2d\u6d77\u8349\u306e3D\u30ad\u30e3\u30ce\u30d4\u30fc\u30e2\u30c7\u30eb\u3092\u4f5c\u6210\u3057\u3001\u9ad8\u89e3\u50cf\u5ea6LiDAR\u3067\u70ad\u7d20\u84c4\u7a4d\u91cf\u3092\u5b9a\u91cf\u5316\u3057\u305f\u65b9\u6cd5\u3092\u3054\u89a7\u304f\u3060\u3055\u3044\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"YellowScan Navigator LiDAR\u306b\u3088\u308b\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u6d77\u8349\u751f\u614b\u7cfb\u306e\u30de\u30c3\u30d4\u30f3\u30b0 - YellowScan\" \/>\n<meta property=\"og:description\" content=\"NIVA\u304cYellowScan Navigator\u3092\u4f7f\u3063\u3066\u6c34\u4e2d\u6d77\u8349\u306e3D\u30ad\u30e3\u30ce\u30d4\u30fc\u30e2\u30c7\u30eb\u3092\u4f5c\u6210\u3057\u3001\u9ad8\u89e3\u50cf\u5ea6LiDAR\u3067\u70ad\u7d20\u84c4\u7a4d\u91cf\u3092\u5b9a\u91cf\u5316\u3057\u305f\u65b9\u6cd5\u3092\u3054\u89a7\u304f\u3060\u3055\u3044\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/\" \/>\n<meta property=\"og:site_name\" content=\"YellowScan\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T14:52:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/ys_website_banner_knowledge_20251007.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/knowledge\\\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\\\/\",\"url\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/knowledge\\\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\\\/\",\"name\":\"YellowScan Navigator LiDAR\u306b\u3088\u308b\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u6d77\u8349\u751f\u614b\u7cfb\u306e\u30de\u30c3\u30d4\u30f3\u30b0 - YellowScan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/knowledge\\\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/knowledge\\\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yellowscan.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ys_website_banner_knowledge_20251007.jpg\",\"datePublished\":\"2025-11-10T14:51:38+00:00\",\"dateModified\":\"2025-11-10T14:52:36+00:00\",\"description\":\"NIVA\u304cYellowScan Navigator\u3092\u4f7f\u3063\u3066\u6c34\u4e2d\u6d77\u8349\u306e3D\u30ad\u30e3\u30ce\u30d4\u30fc\u30e2\u30c7\u30eb\u3092\u4f5c\u6210\u3057\u3001\u9ad8\u89e3\u50cf\u5ea6LiDAR\u3067\u70ad\u7d20\u84c4\u7a4d\u91cf\u3092\u5b9a\u91cf\u5316\u3057\u305f\u65b9\u6cd5\u3092\u3054\u89a7\u304f\u3060\u3055\u3044\u3002\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/knowledge\\\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/knowledge\\\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/knowledge\\\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yellowscan.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ys_website_banner_knowledge_20251007.jpg\",\"contentUrl\":\"https:\\\/\\\/www.yellowscan.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ys_website_banner_knowledge_20251007.jpg\",\"width\":1150,\"height\":600,\"caption\":\"3D canopy models of submerged seagrass made by YellowScan Navigator\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/knowledge\\\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"YellowScan Navigator LiDAR\u306b\u3088\u308b\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u6d77\u8349\u751f\u614b\u7cfb\u306e\u30de\u30c3\u30d4\u30f3\u30b0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/\",\"name\":\"YellowScan\",\"description\":\"Reliable UAV LiDAR systems for Drone 3D laser mapping\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yellowscan.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"YellowScan Navigator LiDAR\u306b\u3088\u308b\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u6d77\u8349\u751f\u614b\u7cfb\u306e\u30de\u30c3\u30d4\u30f3\u30b0 - YellowScan","description":"NIVA\u304cYellowScan Navigator\u3092\u4f7f\u3063\u3066\u6c34\u4e2d\u6d77\u8349\u306e3D\u30ad\u30e3\u30ce\u30d4\u30fc\u30e2\u30c7\u30eb\u3092\u4f5c\u6210\u3057\u3001\u9ad8\u89e3\u50cf\u5ea6LiDAR\u3067\u70ad\u7d20\u84c4\u7a4d\u91cf\u3092\u5b9a\u91cf\u5316\u3057\u305f\u65b9\u6cd5\u3092\u3054\u89a7\u304f\u3060\u3055\u3044\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/","og_locale":"ja_JP","og_type":"article","og_title":"YellowScan Navigator LiDAR\u306b\u3088\u308b\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u6d77\u8349\u751f\u614b\u7cfb\u306e\u30de\u30c3\u30d4\u30f3\u30b0 - YellowScan","og_description":"NIVA\u304cYellowScan Navigator\u3092\u4f7f\u3063\u3066\u6c34\u4e2d\u6d77\u8349\u306e3D\u30ad\u30e3\u30ce\u30d4\u30fc\u30e2\u30c7\u30eb\u3092\u4f5c\u6210\u3057\u3001\u9ad8\u89e3\u50cf\u5ea6LiDAR\u3067\u70ad\u7d20\u84c4\u7a4d\u91cf\u3092\u5b9a\u91cf\u5316\u3057\u305f\u65b9\u6cd5\u3092\u3054\u89a7\u304f\u3060\u3055\u3044\u3002","og_url":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/","og_site_name":"YellowScan","article_modified_time":"2025-11-10T14:52:36+00:00","og_image":[{"width":1150,"height":600,"url":"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/ys_website_banner_knowledge_20251007.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/","url":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/","name":"YellowScan Navigator LiDAR\u306b\u3088\u308b\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u6d77\u8349\u751f\u614b\u7cfb\u306e\u30de\u30c3\u30d4\u30f3\u30b0 - YellowScan","isPartOf":{"@id":"https:\/\/www.yellowscan.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/#primaryimage"},"image":{"@id":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/ys_website_banner_knowledge_20251007.jpg","datePublished":"2025-11-10T14:51:38+00:00","dateModified":"2025-11-10T14:52:36+00:00","description":"NIVA\u304cYellowScan Navigator\u3092\u4f7f\u3063\u3066\u6c34\u4e2d\u6d77\u8349\u306e3D\u30ad\u30e3\u30ce\u30d4\u30fc\u30e2\u30c7\u30eb\u3092\u4f5c\u6210\u3057\u3001\u9ad8\u89e3\u50cf\u5ea6LiDAR\u3067\u70ad\u7d20\u84c4\u7a4d\u91cf\u3092\u5b9a\u91cf\u5316\u3057\u305f\u65b9\u6cd5\u3092\u3054\u89a7\u304f\u3060\u3055\u3044\u3002","breadcrumb":{"@id":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/#primaryimage","url":"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/ys_website_banner_knowledge_20251007.jpg","contentUrl":"https:\/\/www.yellowscan.com\/wp-content\/uploads\/2025\/11\/ys_website_banner_knowledge_20251007.jpg","width":1150,"height":600,"caption":"3D canopy models of submerged seagrass made by YellowScan Navigator"},{"@type":"BreadcrumbList","@id":"https:\/\/www.yellowscan.com\/ja\/knowledge\/mapping-seagrass-ecosystems-in-norway-with-the-yellowscan-navigator-lidar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.yellowscan.com\/ja\/"},{"@type":"ListItem","position":2,"name":"YellowScan Navigator LiDAR\u306b\u3088\u308b\u30ce\u30eb\u30a6\u30a7\u30fc\u306e\u6d77\u8349\u751f\u614b\u7cfb\u306e\u30de\u30c3\u30d4\u30f3\u30b0"}]},{"@type":"WebSite","@id":"https:\/\/www.yellowscan.com\/ja\/#website","url":"https:\/\/www.yellowscan.com\/ja\/","name":"YellowScan","description":"Reliable UAV LiDAR systems for Drone 3D laser mapping","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yellowscan.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/www.yellowscan.com\/ja\/wp-json\/wp\/v2\/ys_knowledge\/25201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yellowscan.com\/ja\/wp-json\/wp\/v2\/ys_knowledge"}],"about":[{"href":"https:\/\/www.yellowscan.com\/ja\/wp-json\/wp\/v2\/types\/ys_knowledge"}],"version-history":[{"count":1,"href":"https:\/\/www.yellowscan.com\/ja\/wp-json\/wp\/v2\/ys_knowledge\/25201\/revisions"}],"predecessor-version":[{"id":25202,"href":"https:\/\/www.yellowscan.com\/ja\/wp-json\/wp\/v2\/ys_knowledge\/25201\/revisions\/25202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yellowscan.com\/ja\/wp-json\/wp\/v2\/media\/25161"}],"wp:attachment":[{"href":"https:\/\/www.yellowscan.com\/ja\/wp-json\/wp\/v2\/media?parent=25201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yellowscan.com\/ja\/wp-json\/wp\/v2\/categories?post=25201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}